{"id":131,"count":33,"description":"","link":"https:\/\/estheteclinic.com\/de\/category\/haarbehandlungen\/","name":"Haarbehandlungen","slug":"haarbehandlungen","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haarbehandlungen Archives - Startseite<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haarbehandlungen Archives - Startseite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estheteclinic.com\/category\/hair-transplant\/\" \/>\n<meta property=\"og:site_name\" content=\"Startseite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/estheteclinic.com\/category\/hair-transplant\/\",\"url\":\"https:\/\/estheteclinic.com\/category\/hair-transplant\/\",\"name\":\"Haarbehandlungen Archives - Startseite\",\"isPartOf\":{\"@id\":\"https:\/\/estheteclinic.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/estheteclinic.com\/category\/hair-transplant\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/estheteclinic.com\/category\/hair-transplant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/estheteclinic.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hair Treatments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/estheteclinic.com\/#website\",\"url\":\"https:\/\/estheteclinic.com\/\",\"name\":\"Startseite\",\"description\":\"Plastic Surgery &amp; Hair Transplant in Turkey\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/estheteclinic.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haarbehandlungen Archives - Startseite","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Haarbehandlungen Archives - Startseite","og_url":"https:\/\/estheteclinic.com\/category\/hair-transplant\/","og_site_name":"Startseite","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/estheteclinic.com\/category\/hair-transplant\/","url":"https:\/\/estheteclinic.com\/category\/hair-transplant\/","name":"Haarbehandlungen Archives - Startseite","isPartOf":{"@id":"https:\/\/estheteclinic.com\/#website"},"breadcrumb":{"@id":"https:\/\/estheteclinic.com\/category\/hair-transplant\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/estheteclinic.com\/category\/hair-transplant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/estheteclinic.com\/de\/"},{"@type":"ListItem","position":2,"name":"Hair Treatments"}]},{"@type":"WebSite","@id":"https:\/\/estheteclinic.com\/#website","url":"https:\/\/estheteclinic.com\/","name":"Startseite","description":"Plastic Surgery &amp; Hair Transplant in Turkey","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estheteclinic.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/estheteclinic.com\/de\/wp-json\/wp\/v2\/categories\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estheteclinic.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/estheteclinic.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/estheteclinic.com\/de\/wp-json\/wp\/v2\/posts?categories=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}